{"id":17510,"date":"2020-06-30T11:25:08","date_gmt":"2020-06-30T09:25:08","guid":{"rendered":"https:\/\/www.gutenberg-gym.de\/?p=17510"},"modified":"2020-07-06T19:11:48","modified_gmt":"2020-07-06T17:11:48","slug":"11-abiturientinnen-erhalten-mit-dem-reifezeugnis-auch-ihr-diplome-du-baccalaureat","status":"publish","type":"post","link":"https:\/\/gutenberg-alt.wiesan.de\/hp\/2020\/06\/11-abiturientinnen-erhalten-mit-dem-reifezeugnis-auch-ihr-diplome-du-baccalaureat\/","title":{"rendered":"11 Abiturient*innen erhalten mit dem Reifezeugnis auch ihr Dipl\u00f4me du Baccalaur\u00e9at"},"content":{"rendered":"<p>Es war im Juni 2010, als die ersten 16 Sch\u00fclerinnen und Sch\u00fcler der Gutenbergschule den deutsch-franz\u00f6sischen Doppelabschluss AbiBac erhielten.<\/p>\n<p>Seither haben insgesamt 147 Abiturientinnen und Abiturienten ihre Pr\u00fcfungen abgelegt und alle haben ihren Doppelabschluss &#8211; deutsches Abitur plus franz\u00f6sische Hochschulreife Baccalaur\u00e9at &#8211; bestanden. Unsere Bacheliers geh\u00f6ren jedes Jahr zu den engagiertesten und besten Abiturienten des Jahrgangs.<\/p>\n<p>In diesem Jahr gab es zun\u00e4chst einige Fragezeichen, was die Durchf\u00fchrung der m\u00fcndlichen Pr\u00fcfungen betraf. Die durch die Covid-19 Pandemie bedingten Reisebeschr\u00e4nkungen machten es unserem franz\u00f6sischen Pr\u00fcfungsbeauftragten Herrn Bouchoucha von der franz\u00f6sischen Schulaufsicht in Stra\u00dfburg leider unm\u00f6glich, selbst die Pr\u00fcfungen abzunehmen. Deshalb beauftragte er die Fachbereichsleiterin Frau Termer mit der Durchf\u00fchrung des franz\u00f6sischen Pr\u00fcfungsteils. In den Pr\u00fcfungen stellten alle Kandidat*innen ihre ausgezeichneten Franz\u00f6sischkenntnisse sowie ihre hervorragenden fachlichen und interkulturellen F\u00e4higkeiten unter Beweis. Folglich gab es in diesem Jahr sogar gleich viermal die h\u00f6chste Auszeichnung \u2013 die \u201emention tr\u00e8s bien\u201c.<\/p>\n<p>Wir gratulieren allen 11 Absolvent*innen ganz herzlich zu ihren tollen Leistungen. Es handelt sich um: <strong>Sophia Bouhaha, Celia Compton, Marion Fezeu, Cl\u00e9ment Hassenfratz, Jule Hein, Emily Hoquante, Ricarda Mencke, Gaspard Oppenh\u00e4user, Lona Marie Rolle, Maria Schmal und Despina Suchier<\/strong>.<\/p>\n<p>Die feierliche \u00dcbergabe der franz\u00f6sischen Zeugnisse erfolgte im festlichen Rahmen der Akademischen Feier in der Lutherkirche am 24. Juni 2020.<\/p>\n<p><a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone  wp-image-17528\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-300x151.jpg\" alt=\"\" width=\"298\" height=\"150\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-300x151.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-1024x514.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-768x386.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-1536x771.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/07\/AbiBac-2020.-2048x1028.jpg 2048w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es war im Juni 2010, als die ersten 16 Sch\u00fclerinnen und Sch\u00fcler der Gutenbergschule den deutsch-franz\u00f6sischen Doppelabschluss AbiBac erhielten. Seither haben insgesamt 147 Abiturientinnen und Abiturienten ihre Pr\u00fcfungen abgelegt und alle haben ihren Doppelabschluss &#8211; deutsches Abitur plus franz\u00f6sische Hochschulreife Baccalaur\u00e9at &#8211; bestanden. Unsere Bacheliers geh\u00f6ren jedes Jahr zu den engagiertesten und besten Abiturienten des [&hellip;]<\/p>\n","protected":false},"author":41,"featured_media":17528,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1,30,21,15,9],"tags":[],"_links":{"self":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17510"}],"collection":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/users\/41"}],"replies":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/comments?post=17510"}],"version-history":[{"count":5,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17510\/revisions"}],"predecessor-version":[{"id":17530,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17510\/revisions\/17530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/media\/17528"}],"wp:attachment":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/media?parent=17510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/categories?post=17510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/tags?post=17510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}