{"id":17953,"date":"2020-12-02T11:05:28","date_gmt":"2020-12-02T10:05:28","guid":{"rendered":"https:\/\/www.gutenberg-gym.de\/?p=17953"},"modified":"2020-12-02T11:05:28","modified_gmt":"2020-12-02T10:05:28","slug":"was-hat-die-weisse-rose-mit-uns-zu-tun-eindrucksvolle-auffuehrung-des-staatstheaters-wiesbaden-im-jahrgang-8","status":"publish","type":"post","link":"https:\/\/gutenberg-alt.wiesan.de\/hp\/2020\/12\/was-hat-die-weisse-rose-mit-uns-zu-tun-eindrucksvolle-auffuehrung-des-staatstheaters-wiesbaden-im-jahrgang-8\/","title":{"rendered":"Was hat die Wei\u00dfe Rose mit uns zu tun? &#8211; Eindrucksvolle Auff\u00fchrung des Staatstheaters Wiesbaden im Jahrgang 8"},"content":{"rendered":"<p>Am Donnerstag, den 5.11., wurde erstmals das das St\u00fcck \u201eDie Wei\u00dfe Rose \u2013 lebt\u201c vom Staatstheater Wiesbaden an unserer Schule vor einem gemischten Religionskurs der 8.Klasse aufgef\u00fchrt. Bei uns waren Yasmin Malina und Paul Sch\u00f6n als Darsteller, Laura zur Nieden, die Theaterp\u00e4dagogin, und die Inszenatorin des St\u00fcckes, Sophie Pompe. Das Ganze fand nat\u00fcrlich unter strengen Hygiene-Ma\u00dfnahmen statt und wurde von Frau Rosenbaum und Herrn Dr. Buchwaldt begleitet.<\/p>\n<p>Wir als Zuschauer waren nicht eingeweiht, worum es gehen sollte, und waren entsprechend \u00fcberrascht, als zwei sehr aufgeregte Sch\u00fcler mit Versp\u00e4tung ins Klassenzimmer kamen und insgesamt eher unseri\u00f6s wirkten. Sie stellten sich als Manni und Sophie vor und waren ziemlich abgelenkt, da Sophie nur Minuten vorher wegen ihrer Anti-Rassismus-Pins am Rucksack die Treppe runtergeschubst worden war. Sie erz\u00e4hlten uns, dass sie f\u00fcr ihre Theater-Gruppe Darsteller suchten und begannen, uns ein St\u00fcck vorzuspielen. Erst da haben die meisten von uns gemerkt, dass die gesamte Szene vorher nur inszeniert gewesen war. Das St\u00fcck handelte von den Geschwistern Scholl, und nach und nach erfuhren wir, wer diese Personen waren. [\u2026]<\/p>\n<p>Das St\u00fcck wurde besonders interessant durch zwei Rollen, die ein Darsteller gleichzeitig spielen musste, auf der einen Seite eines der Scholl-Geschwister und dazu den verplanten Sch\u00fcler. W\u00e4hrend der Auff\u00fchrung gingen immer mal wieder Dinge scheinbar schief, z.B. fehlten Utensilien oder Sophie fielen zwischendurch Puzzleteile zu ihrem eigenen aktuellen Problem mit Nationalsozialismus in ihrem Umfeld ein. Nach und nach erz\u00e4hlten sich beide Geschichten zum gleichen Problem wie von selbst. Das St\u00fcck endete, als es an der Gef\u00e4ngniszellent\u00fcr klopfte, um Hans und Sophie Scholl zu ihrer sp\u00e4teren Hinrichtung zu holen.<\/p>\n<p>Uns alle hat die Geschichte total mitgerissen, und wir waren das ganze St\u00fcck \u00fcber mucksm\u00e4uschenstill, wie sonst eigentlich un\u00fcblich\u2026 Danach hatten wir die M\u00f6glichkeit, unsere pers\u00f6nlichen Erfahrungen und Eindr\u00fccke zu \u00e4u\u00dfern. Ich und viele andere waren sehr beeindruckt von Hans` und Sophies selbstlosen, mutigen und vorbildlichen Verhalten. [\u2026]<br \/>\nDurch die tolle Darstellung ist mir das St\u00fcck sehr gut im Kopf geblieben und hat mich vor allem zum Nachdenken gebracht. Ich frage mich, warum das alles heute immer noch so eine gro\u00dfe Rolle spielen muss. K\u00f6nnen nicht einfach alle so mutig und selbstlos handeln wie Hans und Sophie Scholl? Dann ist mir aber aufgefallen, dass ich daf\u00fcr zun\u00e4chst bei mir selbst anfangen muss. Ich w\u00fcrde zwar nicht sagen, dass ich bei solchen Situationen sonst wegschaue oder noch schlimmer, daran beteiligt bin. Aber ob ich mich trauen w\u00fcrde, selbst direkt etwas dagegen zu tun, auch wenn mir selbst das vielleicht schaden k\u00f6nnte, wei\u00df ich auch nicht. Ich werde nach diesem St\u00fcck keine Gegen-Demonstration gegen\u00fcber Rassisten oder Nazis organisieren, aber mir ist bewusst geworden, dass ich das eigentlich tun sollte und wie viele kleine Dinge ich in meinem und dem anderer Leute allt\u00e4glichen Leben \u00e4ndern kann und werde, um die Welt zu einem besseren Ort zu machen. [\u2026]<\/p>\n<p>(Helena Kampen, 8d)<\/p>\n<p>Pers\u00f6nlich am Spannendesten fand ich aber tats\u00e4chlich, als Sophie und Manni in die Rollen der Geschwister Scholl geschl\u00fcpft sind. Ich fand Sophies und Hans Geschichte so emotional und total traurig. Ich frage mich, wie Menschen so grausam sein k\u00f6nnen. Wie kann man so viele Menschenleben beenden, als seien sie nichts wert? Wie kann man Menschen daf\u00fcr umbringen, dass sie die Wahrheit sagen? F\u00fcr mich ist das nicht nachvollziehbar und wir m\u00fcssen daf\u00fcr k\u00e4mpfen, nicht wieder so zu enden. Denn keiner von uns m\u00f6chte das unterst\u00fctzen, was Hitler getan hat, da bin ich mir sicher. Aber warum denken dann viele Menschen, sie m\u00fcssten ein Hakenkreuz an W\u00e4nde malen oder die Nazis unterst\u00fctzen? Wollen diese Menschen wirklich diese Brutalit\u00e4t und Grausamkeit von damals unterst\u00fctzen? So viele Unschuldige sind f\u00fcr Hitler gestorben. So viele Menschen verloren alles durch seine Taten und heute \u2013 wo wir genau das nicht mehr wollen, verfallen einige von uns wieder in dieses Strickmuster, auch wenn sie es \u201cnicht so meinen\u201d. Aber mit den kleinen Dingen f\u00e4ngt es an \u2013 Menschen mit anderer Hautfarbe oder Herkunft anders zu behandeln als uns. Oder Leute zu diskriminieren, weil sie \u201canders\u201d sind. Ist das nicht schon eine Vorstufe des \u00fcblen Rassismus, mit dem Juden zu k\u00e4mpfen hatten? Wir sollten also aufpassen, was wir tun und uns Hans und Sophies und Worte und Taten und nat\u00fcrlich auch die, aller anderen Aktivist*innen zu Herzen nehmen, die f\u00fcr Gleichberechtigung und Frieden k\u00e4mpfen! Macht nicht mit bei Rassismus und stellt euch dagegen, denn jeder kann etwas ver\u00e4ndern.<\/p>\n<p>(Luise Kania, 8c)<\/p>\n<p><a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17957\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6487-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17958\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6494-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17959\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6496-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17960\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6499-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17961\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6501-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-scaled.jpg\"><img loading=\"lazy\" class=\"alignnone size-medium wp-image-17962\" src=\"https:\/\/www.gutenberg-gym.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-300x170.jpg 300w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-1024x580.jpg 1024w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-768x435.jpg 768w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-1536x869.jpg 1536w, https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-content\/uploads\/2020\/12\/DSC6502-2048x1159.jpg 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am Donnerstag, den 5.11., wurde erstmals das das St\u00fcck \u201eDie Wei\u00dfe Rose \u2013 lebt\u201c vom Staatstheater Wiesbaden an unserer Schule vor einem gemischten Religionskurs der 8.Klasse aufgef\u00fchrt. Bei uns waren Yasmin Malina und Paul Sch\u00f6n als Darsteller, Laura zur Nieden, die Theaterp\u00e4dagogin, und die Inszenatorin des St\u00fcckes, Sophie Pompe. Das Ganze fand nat\u00fcrlich unter strengen [&hellip;]<\/p>\n","protected":false},"author":2625,"featured_media":17961,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17953"}],"collection":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/users\/2625"}],"replies":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/comments?post=17953"}],"version-history":[{"count":1,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17953\/revisions"}],"predecessor-version":[{"id":17963,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/posts\/17953\/revisions\/17963"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/media\/17961"}],"wp:attachment":[{"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/media?parent=17953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/categories?post=17953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gutenberg-alt.wiesan.de\/hp\/wp-json\/wp\/v2\/tags?post=17953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}